{"id":1753,"date":"2023-09-26T09:29:03","date_gmt":"2023-09-26T12:29:03","guid":{"rendered":"https:\/\/eurolatinstudies.com\/post_262\/sem-categoria\/"},"modified":"2024-04-05T19:14:50","modified_gmt":"2024-04-05T22:14:50","slug":"post_262","status":"publish","type":"post","link":"https:\/\/eurolatinstudies.com\/es\/post_262\/","title":{"rendered":"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":2469,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-observatory"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"laces\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/eurolatinstudies.com\/es\/post_262\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Latin American Center of European Studies -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina - Latin American Center of European Studies\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eurolatinstudies.com\/es\/post_262\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-09-26T12:29:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-05T22:14:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina - Latin American Center of European Studies\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/#blogposting\",\"name\":\"O direito \\u00e0 educa\\u00e7\\u00e3o de crian\\u00e7as e de adolescentes migrantes, refugiados e ap\\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\\u00e1 e em Santa Catarina - Latin American Center of European Studies\",\"headline\":\"O direito \\u00e0 educa\\u00e7\\u00e3o de crian\\u00e7as e de adolescentes migrantes, refugiados e ap\\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\\u00e1 e em Santa Catarina\",\"author\":{\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/author\\\/laces\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eurolatinstudies.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/6512d6bfafb72livro-com-fundo-de-placa-verde-scaled.jpg\",\"width\":2560,\"height\":1709,\"caption\":\"book with green board background\"},\"datePublished\":\"2023-09-26T09:29:03-03:00\",\"dateModified\":\"2024-04-05T19:14:50-03:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/#webpage\"},\"articleSection\":\"Observatory\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/category\\\/observatory\\\/#listItem\",\"name\":\"Observatory\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/category\\\/observatory\\\/#listItem\",\"position\":2,\"name\":\"Observatory\",\"item\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/category\\\/observatory\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/#listItem\",\"name\":\"O direito \\u00e0 educa\\u00e7\\u00e3o de crian\\u00e7as e de adolescentes migrantes, refugiados e ap\\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\\u00e1 e em Santa Catarina\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/#listItem\",\"position\":3,\"name\":\"O direito \\u00e0 educa\\u00e7\\u00e3o de crian\\u00e7as e de adolescentes migrantes, refugiados e ap\\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\\u00e1 e em Santa Catarina\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/category\\\/observatory\\\/#listItem\",\"name\":\"Observatory\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/#organization\",\"name\":\"Latin American Center of European Studies\",\"url\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/author\\\/laces\\\/#author\",\"url\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/author\\\/laces\\\/\",\"name\":\"laces\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/#webpage\",\"url\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/\",\"name\":\"O direito \\u00e0 educa\\u00e7\\u00e3o de crian\\u00e7as e de adolescentes migrantes, refugiados e ap\\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\\u00e1 e em Santa Catarina - Latin American Center of European Studies\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/author\\\/laces\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/author\\\/laces\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eurolatinstudies.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/6512d6bfafb72livro-com-fundo-de-placa-verde-scaled.jpg\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/#mainImage\",\"width\":2560,\"height\":1709,\"caption\":\"book with green board background\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/post_262\\\/#mainImage\"},\"datePublished\":\"2023-09-26T09:29:03-03:00\",\"dateModified\":\"2024-04-05T19:14:50-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/\",\"name\":\"Latin American Center of European Studies\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eurolatinstudies.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina - Latin American Center of European Studies","description":"","canonical_url":"https:\/\/eurolatinstudies.com\/es\/post_262\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/eurolatinstudies.com\/es\/post_262\/#blogposting","name":"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina - Latin American Center of European Studies","headline":"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina","author":{"@id":"https:\/\/eurolatinstudies.com\/es\/author\/laces\/#author"},"publisher":{"@id":"https:\/\/eurolatinstudies.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eurolatinstudies.com\/wp-content\/uploads\/2024\/02\/6512d6bfafb72livro-com-fundo-de-placa-verde-scaled.jpg","width":2560,"height":1709,"caption":"book with green board background"},"datePublished":"2023-09-26T09:29:03-03:00","dateModified":"2024-04-05T19:14:50-03:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eurolatinstudies.com\/es\/post_262\/#webpage"},"isPartOf":{"@id":"https:\/\/eurolatinstudies.com\/es\/post_262\/#webpage"},"articleSection":"Observatory"},{"@type":"BreadcrumbList","@id":"https:\/\/eurolatinstudies.com\/es\/post_262\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eurolatinstudies.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/eurolatinstudies.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eurolatinstudies.com\/es\/category\/observatory\/#listItem","name":"Observatory"}},{"@type":"ListItem","@id":"https:\/\/eurolatinstudies.com\/es\/category\/observatory\/#listItem","position":2,"name":"Observatory","item":"https:\/\/eurolatinstudies.com\/es\/category\/observatory\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eurolatinstudies.com\/es\/post_262\/#listItem","name":"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eurolatinstudies.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eurolatinstudies.com\/es\/post_262\/#listItem","position":3,"name":"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina","previousItem":{"@type":"ListItem","@id":"https:\/\/eurolatinstudies.com\/es\/category\/observatory\/#listItem","name":"Observatory"}}]},{"@type":"Organization","@id":"https:\/\/eurolatinstudies.com\/es\/#organization","name":"Latin American Center of European Studies","url":"https:\/\/eurolatinstudies.com\/es\/"},{"@type":"Person","@id":"https:\/\/eurolatinstudies.com\/es\/author\/laces\/#author","url":"https:\/\/eurolatinstudies.com\/es\/author\/laces\/","name":"laces"},{"@type":"WebPage","@id":"https:\/\/eurolatinstudies.com\/es\/post_262\/#webpage","url":"https:\/\/eurolatinstudies.com\/es\/post_262\/","name":"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina - Latin American Center of European Studies","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eurolatinstudies.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/eurolatinstudies.com\/es\/post_262\/#breadcrumblist"},"author":{"@id":"https:\/\/eurolatinstudies.com\/es\/author\/laces\/#author"},"creator":{"@id":"https:\/\/eurolatinstudies.com\/es\/author\/laces\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eurolatinstudies.com\/wp-content\/uploads\/2024\/02\/6512d6bfafb72livro-com-fundo-de-placa-verde-scaled.jpg","@id":"https:\/\/eurolatinstudies.com\/es\/post_262\/#mainImage","width":2560,"height":1709,"caption":"book with green board background"},"primaryImageOfPage":{"@id":"https:\/\/eurolatinstudies.com\/es\/post_262\/#mainImage"},"datePublished":"2023-09-26T09:29:03-03:00","dateModified":"2024-04-05T19:14:50-03:00"},{"@type":"WebSite","@id":"https:\/\/eurolatinstudies.com\/es\/#website","url":"https:\/\/eurolatinstudies.com\/es\/","name":"Latin American Center of European Studies","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eurolatinstudies.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Latin American Center of European Studies -","og:type":"article","og:title":"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina - Latin American Center of European Studies","og:url":"https:\/\/eurolatinstudies.com\/es\/post_262\/","article:published_time":"2023-09-26T12:29:03+00:00","article:modified_time":"2024-04-05T22:14:50+00:00","twitter:card":"summary_large_image","twitter:title":"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina - Latin American Center of European Studies"},"aioseo_meta_data":{"post_id":"1753","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-01-15 03:48:23","updated":"2025-06-05 00:19:28","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eurolatinstudies.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eurolatinstudies.com\/es\/category\/observatory\/\" title=\"Observatory\">Observatory<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tO direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eurolatinstudies.com\/es\/"},{"label":"Observatory","link":"https:\/\/eurolatinstudies.com\/es\/category\/observatory\/"},{"label":"O direito \u00e0 educa\u00e7\u00e3o de crian\u00e7as e de adolescentes migrantes, refugiados e ap\u00e1tridas: uma necessidade mundial e seus reflexos no Paran\u00e1 e em Santa Catarina","link":"https:\/\/eurolatinstudies.com\/es\/post_262\/"}],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/posts\/1753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/comments?post=1753"}],"version-history":[{"count":1,"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/posts\/1753\/revisions"}],"predecessor-version":[{"id":5226,"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/posts\/1753\/revisions\/5226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/media\/2469"}],"wp:attachment":[{"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/media?parent=1753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/categories?post=1753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eurolatinstudies.com\/es\/wp-json\/wp\/v2\/tags?post=1753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}